{"id":98,"count":349,"description":"","link":"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/","name":"CDs, DVDs","slug":"cds-dvds","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<title>CD et DVD de musique de harpe - Boutique en ligne Camac<\/title>\n<meta name=\"description\" content=\"CD et DVD de musique de harpe | Livraison dans le monde entier | Vaste s\u00e9lection des meilleures musiques de harpe classique, celtique, jazz, pop et rock.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CD et DVD de musique de harpe - Boutique en ligne Camac\" \/>\n<meta property=\"og:description\" content=\"CD et DVD de musique de harpe | Livraison dans le monde entier | Vaste s\u00e9lection des meilleures musiques de harpe classique, celtique, jazz, pop et rock.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/\" \/>\n<meta property=\"og:site_name\" content=\"Camac Harps Shop\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/category\\\/cds-dvds\\\/\",\"url\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/category\\\/cds-dvds\\\/\",\"name\":\"CD et DVD de musique de harpe - Boutique en ligne Camac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/#website\"},\"description\":\"CD et DVD de musique de harpe | Livraison dans le monde entier | Vaste s\u00e9lection des meilleures musiques de harpe classique, celtique, jazz, pop et rock.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/category\\\/cds-dvds\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/category\\\/cds-dvds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CDs, DVDs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/\",\"name\":\"Camac Harps Shop\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.camac-harps.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>","yoast_head_json":{"title":"CD et DVD de musique de harpe - Boutique en ligne Camac","description":"CD et DVD de musique de harpe | Livraison dans le monde entier | Vaste s\u00e9lection des meilleures musiques de harpe classique, celtique, jazz, pop et rock.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/","og_locale":"de_DE","og_type":"article","og_title":"CD et DVD de musique de harpe - Boutique en ligne Camac","og_description":"CD et DVD de musique de harpe | Livraison dans le monde entier | Vaste s\u00e9lection des meilleures musiques de harpe classique, celtique, jazz, pop et rock.","og_url":"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/","og_site_name":"Camac Harps Shop","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/","url":"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/","name":"CD et DVD de musique de harpe - Boutique en ligne Camac","isPartOf":{"@id":"https:\/\/shop.camac-harps.com\/de\/#website"},"description":"CD et DVD de musique de harpe | Livraison dans le monde entier | Vaste s\u00e9lection des meilleures musiques de harpe classique, celtique, jazz, pop et rock.","breadcrumb":{"@id":"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/shop.camac-harps.com\/de\/category\/cds-dvds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shop.camac-harps.com\/de\/"},{"@type":"ListItem","position":2,"name":"CDs, DVDs"}]},{"@type":"WebSite","@id":"https:\/\/shop.camac-harps.com\/de\/#website","url":"https:\/\/shop.camac-harps.com\/de\/","name":"Camac Harps Shop","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.camac-harps.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/shop.camac-harps.com\/de\/wp-json\/wp\/v2\/product_cat\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.camac-harps.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/shop.camac-harps.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/shop.camac-harps.com\/de\/wp-json\/wp\/v2\/product?product_cat=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}